{"id":107,"count":8,"description":"","link":"https:\/\/countryhouseilfaeto.it\/en\/category\/activities\/","name":"Activities","slug":"activities","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Activities Archivi | Country House Il Faeto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/countryhouseilfaeto.it\/en\/category\/activities\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Activities Archivi | Country House Il Faeto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/countryhouseilfaeto.it\/en\/category\/activities\/\" \/>\n<meta property=\"og:site_name\" content=\"Country House Il Faeto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/en\\\/category\\\/activities\\\/\",\"url\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/en\\\/category\\\/activities\\\/\",\"name\":\"Activities Archivi | Country House Il Faeto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/en\\\/category\\\/activities\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/en\\\/category\\\/activities\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activities\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/#website\",\"url\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/\",\"name\":\"Country House Il Faeto\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/#organization\",\"name\":\"Il Faeto\",\"url\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Logo-Il-Faeto.png\",\"contentUrl\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Logo-Il-Faeto.png\",\"width\":644,\"height\":421,\"caption\":\"Il Faeto\"},\"image\":{\"@id\":\"https:\\\/\\\/countryhouseilfaeto.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/countryhouseilfaeto\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ilfaeto\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@countryhouseilfaeto8242\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Activities Archivi | Country House Il Faeto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/countryhouseilfaeto.it\/en\/category\/activities\/","og_locale":"en_US","og_type":"article","og_title":"Activities Archivi | Country House Il Faeto","og_url":"https:\/\/countryhouseilfaeto.it\/en\/category\/activities\/","og_site_name":"Country House Il Faeto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/countryhouseilfaeto.it\/en\/category\/activities\/","url":"https:\/\/countryhouseilfaeto.it\/en\/category\/activities\/","name":"Activities Archivi | Country House Il Faeto","isPartOf":{"@id":"https:\/\/countryhouseilfaeto.it\/#website"},"breadcrumb":{"@id":"https:\/\/countryhouseilfaeto.it\/en\/category\/activities\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/countryhouseilfaeto.it\/en\/category\/activities\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/countryhouseilfaeto.it\/"},{"@type":"ListItem","position":2,"name":"Activities"}]},{"@type":"WebSite","@id":"https:\/\/countryhouseilfaeto.it\/#website","url":"https:\/\/countryhouseilfaeto.it\/","name":"Country House Il Faeto","description":"","publisher":{"@id":"https:\/\/countryhouseilfaeto.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/countryhouseilfaeto.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/countryhouseilfaeto.it\/#organization","name":"Il Faeto","url":"https:\/\/countryhouseilfaeto.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/countryhouseilfaeto.it\/#\/schema\/logo\/image\/","url":"https:\/\/countryhouseilfaeto.it\/wp-content\/uploads\/2023\/03\/Logo-Il-Faeto.png","contentUrl":"https:\/\/countryhouseilfaeto.it\/wp-content\/uploads\/2023\/03\/Logo-Il-Faeto.png","width":644,"height":421,"caption":"Il Faeto"},"image":{"@id":"https:\/\/countryhouseilfaeto.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/countryhouseilfaeto\/","https:\/\/www.instagram.com\/ilfaeto\/","https:\/\/www.youtube.com\/@countryhouseilfaeto8242"]}]}},"_links":{"self":[{"href":"https:\/\/countryhouseilfaeto.it\/en\/wp-json\/wp\/v2\/categories\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/countryhouseilfaeto.it\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/countryhouseilfaeto.it\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/countryhouseilfaeto.it\/en\/wp-json\/wp\/v2\/posts?categories=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}